{"id":48484,"date":"2026-07-14T20:12:13","date_gmt":"2026-07-14T17:12:13","guid":{"rendered":"https:\/\/flower-hasa.com\/?post_type=product&#038;p=48484"},"modified":"2026-07-14T20:14:19","modified_gmt":"2026-07-14T17:14:19","slug":"%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7","status":"publish","type":"product","link":"https:\/\/flower-hasa.com\/en\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/","title":{"rendered":"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":48483,"template":"","meta":[],"product_brand":[],"product_cat":[85],"product_tag":[],"class_list":["post-48484","product","type-product","status-publish","has-post-thumbnail","product_cat-bokehat","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627 - Flower Hasa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flower-hasa.com\/en\/product\/\u0628\u0648\u0643\u064a\u0647-\u062c\u0631\u0628\u064a\u0631\u0627\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627 - Flower Hasa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flower-hasa.com\/en\/product\/\u0628\u0648\u0643\u064a\u0647-\u062c\u0631\u0628\u064a\u0631\u0627\/\" \/>\n<meta property=\"og:site_name\" content=\"Flower Hasa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T17:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flower-hasa.com\/wp-content\/uploads\/2026\/07\/IMG_8462-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/\",\"url\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/\",\"name\":\"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627 - Flower Hasa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/flower-hasa.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_8462-scaled.jpeg\",\"datePublished\":\"2026-07-14T17:12:13+00:00\",\"dateModified\":\"2026-07-14T17:14:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/flower-hasa.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_8462-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/flower-hasa.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/IMG_8462-scaled.jpeg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/product\\\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/flower-hasa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/flower-hasa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/flower-hasa.com\\\/#website\",\"url\":\"https:\\\/\\\/flower-hasa.com\\\/\",\"name\":\"Flower Hasa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/flower-hasa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627 - Flower Hasa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flower-hasa.com\/en\/product\/\u0628\u0648\u0643\u064a\u0647-\u062c\u0631\u0628\u064a\u0631\u0627\/","og_locale":"en_US","og_type":"article","og_title":"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627 - Flower Hasa","og_url":"https:\/\/flower-hasa.com\/en\/product\/\u0628\u0648\u0643\u064a\u0647-\u062c\u0631\u0628\u064a\u0631\u0627\/","og_site_name":"Flower Hasa","article_modified_time":"2026-07-14T17:14:19+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/flower-hasa.com\/wp-content\/uploads\/2026\/07\/IMG_8462-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/","url":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/","name":"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627 - Flower Hasa","isPartOf":{"@id":"https:\/\/flower-hasa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/#primaryimage"},"image":{"@id":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/#primaryimage"},"thumbnailUrl":"https:\/\/flower-hasa.com\/wp-content\/uploads\/2026\/07\/IMG_8462-scaled.jpeg","datePublished":"2026-07-14T17:12:13+00:00","dateModified":"2026-07-14T17:14:19+00:00","breadcrumb":{"@id":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/#primaryimage","url":"https:\/\/flower-hasa.com\/wp-content\/uploads\/2026\/07\/IMG_8462-scaled.jpeg","contentUrl":"https:\/\/flower-hasa.com\/wp-content\/uploads\/2026\/07\/IMG_8462-scaled.jpeg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/flower-hasa.com\/product\/%d8%a8%d9%88%d9%83%d9%8a%d9%87-%d8%ac%d8%b1%d8%a8%d9%8a%d8%b1%d8%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flower-hasa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/flower-hasa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0628\u0648\u0643\u064a\u0647 \u062c\u0631\u0628\u064a\u0631\u0627"}]},{"@type":"WebSite","@id":"https:\/\/flower-hasa.com\/#website","url":"https:\/\/flower-hasa.com\/","name":"Flower Hasa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flower-hasa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/product\/48484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/media\/48483"}],"wp:attachment":[{"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/media?parent=48484"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/product_brand?post=48484"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/product_cat?post=48484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/flower-hasa.com\/en\/wp-json\/wp\/v2\/product_tag?post=48484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}